{"id":986,"count":1,"description":"","link":"https:\/\/www.metropolis.dk\/en\/tag\/shekufe-tadayoni-heiberg-en\/","name":"Shekufe Tadayoni Heiberg","slug":"shekufe-tadayoni-heiberg-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Shekufe Tadayoni Heiberg - Metropolis<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.metropolis.dk\/en\/tag\/shekufe-tadayoni-heiberg-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Shekufe Tadayoni Heiberg - Metropolis\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.metropolis.dk\/en\/tag\/shekufe-tadayoni-heiberg-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Metropolis\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.metropolis.dk\\\/en\\\/tag\\\/shekufe-tadayoni-heiberg-en\\\/\",\"url\":\"https:\\\/\\\/www.metropolis.dk\\\/en\\\/tag\\\/shekufe-tadayoni-heiberg-en\\\/\",\"name\":\"Shekufe Tadayoni Heiberg - Metropolis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.metropolis.dk\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.metropolis.dk\\\/en\\\/tag\\\/shekufe-tadayoni-heiberg-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.metropolis.dk\\\/en\\\/tag\\\/shekufe-tadayoni-heiberg-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Hjem\",\"item\":\"https:\\\/\\\/www.metropolis.dk\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shekufe Tadayoni Heiberg\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.metropolis.dk\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.metropolis.dk\\\/en\\\/\",\"name\":\"Metropolis\",\"description\":\"performance og kunst i byens rum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.metropolis.dk\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Shekufe Tadayoni Heiberg - Metropolis","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.metropolis.dk\/en\/tag\/shekufe-tadayoni-heiberg-en\/","og_locale":"en_US","og_type":"article","og_title":"Shekufe Tadayoni Heiberg - Metropolis","og_url":"https:\/\/www.metropolis.dk\/en\/tag\/shekufe-tadayoni-heiberg-en\/","og_site_name":"Metropolis","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.metropolis.dk\/en\/tag\/shekufe-tadayoni-heiberg-en\/","url":"https:\/\/www.metropolis.dk\/en\/tag\/shekufe-tadayoni-heiberg-en\/","name":"Shekufe Tadayoni Heiberg - Metropolis","isPartOf":{"@id":"https:\/\/www.metropolis.dk\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.metropolis.dk\/en\/tag\/shekufe-tadayoni-heiberg-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.metropolis.dk\/en\/tag\/shekufe-tadayoni-heiberg-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Hjem","item":"https:\/\/www.metropolis.dk\/en\/"},{"@type":"ListItem","position":2,"name":"Shekufe Tadayoni Heiberg"}]},{"@type":"WebSite","@id":"https:\/\/www.metropolis.dk\/en\/#website","url":"https:\/\/www.metropolis.dk\/en\/","name":"Metropolis","description":"performance og kunst i byens rum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.metropolis.dk\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.metropolis.dk\/en\/wp-json\/wp\/v2\/tags\/986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.metropolis.dk\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.metropolis.dk\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.metropolis.dk\/en\/wp-json\/wp\/v2\/posts?tags=986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}